{"id":34312,"date":"2025-10-02T17:12:33","date_gmt":"2025-10-02T15:12:33","guid":{"rendered":"https:\/\/energysciencefortomorrow.ch\/?p=34312"},"modified":"2025-10-02T17:12:48","modified_gmt":"2025-10-02T15:12:48","slug":"polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat","status":"publish","type":"post","link":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/","title":{"rendered":"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":34317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-34312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen<\/title>\n<meta name=\"description\" content=\"Stromausf\u00e4lle haben Auswirkungen auf den Einzelnen, da sie den Zugang zu Dienstleistungen wie Beleuchtung, Klimatisierung und Kommunikation unterbrechen. In diesem Artikel erl\u00e4utern wir, wie sich Stromausf\u00e4lle auf den Einzelnen auswirken, wie wir die Auswirkungen von Stromausf\u00e4llen auf den Menschen messen k\u00f6nnen und wie wir den Schaden f\u00fcr den Menschen bei der Planung von Stromnetzen abmildern k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen\" \/>\n<meta property=\"og:description\" content=\"Stromausf\u00e4lle haben Auswirkungen auf den Einzelnen, da sie den Zugang zu Dienstleistungen wie Beleuchtung, Klimatisierung und Kommunikation unterbrechen. In diesem Artikel erl\u00e4utern wir, wie sich Stromausf\u00e4lle auf den Einzelnen auswirken, wie wir die Auswirkungen von Stromausf\u00e4llen auf den Menschen messen k\u00f6nnen und wie wir den Schaden f\u00fcr den Menschen bei der Planung von Stromnetzen abmildern k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/\" \/>\n<meta property=\"og:site_name\" content=\"ES4T\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T15:12:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-02T15:12:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energysciencefortomorrow.ch\/wp-content\/uploads\/2025\/10\/news-ETHZ-power-outages-1024x767.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Laura_Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@energyscienceto\" \/>\n<meta name=\"twitter:site\" content=\"@energyscienceto\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura_Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/\"},\"author\":{\"name\":\"Laura_Admin\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#\\\/schema\\\/person\\\/002f271e3c6a89470c4259bc415cb5f2\"},\"headline\":\"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen\",\"datePublished\":\"2025-10-02T15:12:33+00:00\",\"dateModified\":\"2025-10-02T15:12:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/\"},\"wordCount\":9,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/news-ETHZ-power-outages.png\",\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/\",\"url\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/\",\"name\":\"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/news-ETHZ-power-outages.png\",\"datePublished\":\"2025-10-02T15:12:33+00:00\",\"dateModified\":\"2025-10-02T15:12:48+00:00\",\"description\":\"Stromausf\u00e4lle haben Auswirkungen auf den Einzelnen, da sie den Zugang zu Dienstleistungen wie Beleuchtung, Klimatisierung und Kommunikation unterbrechen. In diesem Artikel erl\u00e4utern wir, wie sich Stromausf\u00e4lle auf den Einzelnen auswirken, wie wir die Auswirkungen von Stromausf\u00e4llen auf den Menschen messen k\u00f6nnen und wie wir den Schaden f\u00fcr den Menschen bei der Planung von Stromnetzen abmildern k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/news-ETHZ-power-outages.png\",\"contentUrl\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/news-ETHZ-power-outages.png\",\"width\":1920,\"height\":1439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/\",\"name\":\"ES4T\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#organization\",\"name\":\"ES4T\",\"url\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/es4t-header-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/es4t-header-logo-01.png\",\"width\":303,\"height\":121,\"caption\":\"ES4T\"},\"image\":{\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/energyscienceto\",\"https:\\\/\\\/www.instagram.com\\\/energysciencefortomorrow\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/energy-science-for-tomorrow\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/energysciencefortomorrow.ch\\\/de\\\/#\\\/schema\\\/person\\\/002f271e3c6a89470c4259bc415cb5f2\",\"name\":\"Laura_Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbf58613382e9c7c35a0d7f0fe3032f2cc02b960536089f0c7d0f7e7011eb8c6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbf58613382e9c7c35a0d7f0fe3032f2cc02b960536089f0c7d0f7e7011eb8c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbf58613382e9c7c35a0d7f0fe3032f2cc02b960536089f0c7d0f7e7011eb8c6?s=96&d=mm&r=g\",\"caption\":\"Laura_Admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen","description":"Stromausf\u00e4lle haben Auswirkungen auf den Einzelnen, da sie den Zugang zu Dienstleistungen wie Beleuchtung, Klimatisierung und Kommunikation unterbrechen. In diesem Artikel erl\u00e4utern wir, wie sich Stromausf\u00e4lle auf den Einzelnen auswirken, wie wir die Auswirkungen von Stromausf\u00e4llen auf den Menschen messen k\u00f6nnen und wie wir den Schaden f\u00fcr den Menschen bei der Planung von Stromnetzen abmildern k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/","og_locale":"de_DE","og_type":"article","og_title":"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen","og_description":"Stromausf\u00e4lle haben Auswirkungen auf den Einzelnen, da sie den Zugang zu Dienstleistungen wie Beleuchtung, Klimatisierung und Kommunikation unterbrechen. In diesem Artikel erl\u00e4utern wir, wie sich Stromausf\u00e4lle auf den Einzelnen auswirken, wie wir die Auswirkungen von Stromausf\u00e4llen auf den Menschen messen k\u00f6nnen und wie wir den Schaden f\u00fcr den Menschen bei der Planung von Stromnetzen abmildern k\u00f6nnen.","og_url":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/","og_site_name":"ES4T","article_published_time":"2025-10-02T15:12:33+00:00","article_modified_time":"2025-10-02T15:12:48+00:00","og_image":[{"width":1024,"height":767,"url":"https:\/\/energysciencefortomorrow.ch\/wp-content\/uploads\/2025\/10\/news-ETHZ-power-outages-1024x767.png","type":"image\/png"}],"author":"Laura_Admin","twitter_card":"summary_large_image","twitter_creator":"@energyscienceto","twitter_site":"@energyscienceto","twitter_misc":{"Verfasst von":"Laura_Admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/#article","isPartOf":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/"},"author":{"name":"Laura_Admin","@id":"https:\/\/energysciencefortomorrow.ch\/de\/#\/schema\/person\/002f271e3c6a89470c4259bc415cb5f2"},"headline":"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen","datePublished":"2025-10-02T15:12:33+00:00","dateModified":"2025-10-02T15:12:48+00:00","mainEntityOfPage":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/"},"wordCount":9,"commentCount":0,"publisher":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/#organization"},"image":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/#primaryimage"},"thumbnailUrl":"https:\/\/energysciencefortomorrow.ch\/wp-content\/uploads\/2025\/10\/news-ETHZ-power-outages.png","articleSection":["Nachrichten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/","url":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/","name":"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen","isPartOf":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/#primaryimage"},"image":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/#primaryimage"},"thumbnailUrl":"https:\/\/energysciencefortomorrow.ch\/wp-content\/uploads\/2025\/10\/news-ETHZ-power-outages.png","datePublished":"2025-10-02T15:12:33+00:00","dateModified":"2025-10-02T15:12:48+00:00","description":"Stromausf\u00e4lle haben Auswirkungen auf den Einzelnen, da sie den Zugang zu Dienstleistungen wie Beleuchtung, Klimatisierung und Kommunikation unterbrechen. In diesem Artikel erl\u00e4utern wir, wie sich Stromausf\u00e4lle auf den Einzelnen auswirken, wie wir die Auswirkungen von Stromausf\u00e4llen auf den Menschen messen k\u00f6nnen und wie wir den Schaden f\u00fcr den Menschen bei der Planung von Stromnetzen abmildern k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/#primaryimage","url":"https:\/\/energysciencefortomorrow.ch\/wp-content\/uploads\/2025\/10\/news-ETHZ-power-outages.png","contentUrl":"https:\/\/energysciencefortomorrow.ch\/wp-content\/uploads\/2025\/10\/news-ETHZ-power-outages.png","width":1920,"height":1439},{"@type":"BreadcrumbList","@id":"https:\/\/energysciencefortomorrow.ch\/de\/polizero-psi-projekt-zeigt-wege-zur-klimaneutralitat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energysciencefortomorrow.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Ber\u00fccksichtigen Sie die menschlichen Auswirkungen von Stromausf\u00e4llen"}]},{"@type":"WebSite","@id":"https:\/\/energysciencefortomorrow.ch\/de\/#website","url":"https:\/\/energysciencefortomorrow.ch\/de\/","name":"ES4T","description":"","publisher":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energysciencefortomorrow.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/energysciencefortomorrow.ch\/de\/#organization","name":"ES4T","url":"https:\/\/energysciencefortomorrow.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/energysciencefortomorrow.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/energysciencefortomorrow.ch\/wp-content\/uploads\/2023\/10\/es4t-header-logo-01.png","contentUrl":"https:\/\/energysciencefortomorrow.ch\/wp-content\/uploads\/2023\/10\/es4t-header-logo-01.png","width":303,"height":121,"caption":"ES4T"},"image":{"@id":"https:\/\/energysciencefortomorrow.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/energyscienceto","https:\/\/www.instagram.com\/energysciencefortomorrow\/","https:\/\/www.linkedin.com\/company\/energy-science-for-tomorrow\/"]},{"@type":"Person","@id":"https:\/\/energysciencefortomorrow.ch\/de\/#\/schema\/person\/002f271e3c6a89470c4259bc415cb5f2","name":"Laura_Admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fbf58613382e9c7c35a0d7f0fe3032f2cc02b960536089f0c7d0f7e7011eb8c6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbf58613382e9c7c35a0d7f0fe3032f2cc02b960536089f0c7d0f7e7011eb8c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbf58613382e9c7c35a0d7f0fe3032f2cc02b960536089f0c7d0f7e7011eb8c6?s=96&d=mm&r=g","caption":"Laura_Admin"}}]}},"_links":{"self":[{"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/posts\/34312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/comments?post=34312"}],"version-history":[{"count":2,"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/posts\/34312\/revisions"}],"predecessor-version":[{"id":34324,"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/posts\/34312\/revisions\/34324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/media\/34317"}],"wp:attachment":[{"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/media?parent=34312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/categories?post=34312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energysciencefortomorrow.ch\/de\/wp-json\/wp\/v2\/tags?post=34312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}